{"id":11540,"date":"2022-06-14T14:38:24","date_gmt":"2022-06-14T12:38:24","guid":{"rendered":"https:\/\/www.noooagency.com\/?post_type=noooborders&#038;p=11540"},"modified":"2026-03-12T18:46:48","modified_gmt":"2026-03-12T17:46:48","slug":"axor-e-nooo-agency-per-un-pulito-sostenibile","status":"publish","type":"noooborders","link":"https:\/\/www.noooagency.com\/noooborders\/axor-e-nooo-agency-per-un-pulito-sostenibile\/","title":{"rendered":"Axor e NOOO Agency per un pulito sostenibile"},"content":{"rendered":"\n<p><strong>Chi \u00e8 Axor&nbsp;<\/strong><br><a href=\"https:\/\/www.axor.net\/\" target=\"_blank\" rel=\"noopener\">Axor<\/a>&nbsp;\u00e8 un\u2019azienda italiana che da pi\u00f9 di 40 anni si occupa di prodotti dedicati alla pulizia di diversi apparecchi domestici e industriali. Mossa fin dall\u2019origine da un profondo senso di responsabilit\u00e0 sociale e ambientale e forte di un\u2019esperienza consolidata nel tempo, Axor ha deciso di intraprendere un nuovo progetto che risponde alla necessit\u00e0 di attivarsi per qualcosa di concreto per salvaguardare l\u2019ambiente.<br><br>Nascono cos\u00ec le&nbsp;<strong>tabs Axor<\/strong>, detergenti in pastiglie solubili in acqua, per promuovere il risparmio e il riciclo delle confezioni in plastica. Il progetto innovativo pone cos\u00ec in primo piano&nbsp;<strong>il tema del riutilizzo<\/strong>, rinunciando alla produzione di flaconi in plastica inutili e offrendo&nbsp;<strong>prodotti per una pulizia pi\u00f9 sostenibile<\/strong>.&nbsp;<br><br><strong>Branding e strategy per prodotti sostenibili&nbsp;<\/strong><br><br>Con Axor, NOOO Agency abbraccia il tema della sostenibilit\u00e0 e coglie l\u2019occasione non solo di dare nuova vita e immagine a un brand, ma anche di raccontare un progetto di valore e contribuire a renderlo concreto.&nbsp;<br><br>La prima fase del progetto \u00e8 consistita in&nbsp;<strong>un\u2019analisi precisa e verticale del settore e del mercato<\/strong>, al fine di comprendere chi fosse il potenziale interlocutore, come raccontare il brand e intercettare le esigenze dei clienti.&nbsp;<strong>All\u2019analisi strategica si \u00e8 affiancata, inoltre, anche quella creativa<\/strong>: bisognava infatti comprendere non solo come Axor sarebbe entrato nella quotidianit\u00e0 delle persone, ma anche in che modo, con che immagine, con che stile visivo e concettuale.&nbsp;<br><br>I&nbsp;<strong>due elementi chiave<\/strong>&nbsp;sui quali \u00e8 stato formulato il concept alla base del progetto sono stati&nbsp;<strong>la pulizia&nbsp;<\/strong>e la necessit\u00e0 di evidenziare&nbsp;<strong>il tema della riduzione dell\u2019impatto ambientale<\/strong>&nbsp;di questi prodotti.&nbsp;<br><strong>Palette di colori accesi<\/strong>, visual astratti,&nbsp;<strong>linee morbide<\/strong>&nbsp;e sensazioni di&nbsp;<strong>leggerezza e freschezza<\/strong>&nbsp;portano cos\u00ec a compimento il nuovo stile creativo di Axor, facendoci entrare in&nbsp;<strong>una dimensione in cui la pulizia si unisce alla sostenibilit\u00e0<\/strong>, rendendoci \u201cpiccoli guardiani per il pianeta\u201d.&nbsp;<br>Sulla base di questo stile creativo, il&nbsp;<strong>logo<\/strong>&nbsp;\u00e8 stato il primo aspetto identificativo creato. Compatto, versatile e leggibile, il nuovo logo Axor unisce logotipo e pittogramma e si lega alla natura mediante la trasformazione della lettera x del naming in un quadrifoglio dalle linee sinuose e geometriche al tempo stesso.&nbsp;<\/p>\n\n\n\n<p>Il secondo step creativo ha visto come protagonista&nbsp;<strong>il colore<\/strong>. Per differenziare le quattro linee di tabs Axor sono state definite altrettante palette,&nbsp;tutte con colori accesi e d\u2019impatto visivo. Verde, giallo, rosa e azzurro entrano cos\u00ec nelle diverse aree domestiche e vanno a colorare packaging e etichette dei prodotti dedicati.&nbsp;<br><br><strong>L\u2019e-commerce: dal web design allo sviluppo&nbsp;<\/strong><br>Una volta data una nuova identit\u00e0 ad Axor, \u00e8 giunto il momento di crearle anche&nbsp;<strong>una nuova presenza online<\/strong>, mediante un sito web che incarnasse e raccontasse la freschezza e la leggerezza alla base del brand e al tempo stesso permettesse ai clienti di poter ordinare direttamente le proprie tabs.&nbsp;<br><br>La seconda fase del progetto ha visto quindi coinvolto il team di web design e sviluppo. Dall\u2019alberatura del sito, alla progettazione dei wireframe, fino allo sviluppo effettivo dell\u2019e-commerce, ogni aspetto ha preso in considerazione&nbsp;<strong>la necessit\u00e0 di avvicinare in modo immediato e funzionale l\u2019utente alla nuova modalit\u00e0 di pulizia proposta da Axor<\/strong>.&nbsp;<br>Per questo si \u00e8 pensato ad<strong>&nbsp;una navigazione intuitiva e semplice<\/strong>, accostata a&nbsp;<strong>uno stile creativo minimal e pulito<\/strong>, ma al tempo stesso riconducibile alla natura del brand.&nbsp;<br>Inoltre, per meglio raccontare la peculiarit\u00e0 del prodotto, il team si \u00e8 anche occupato di&nbsp;<strong>trasporre in <a href=\"https:\/\/www.noooagency.com\/servizi\/shooting-foto-video\/\" target=\"_blank\" rel=\"noreferrer noopener\">video animato<\/a> il funzionamento delle tabs<\/strong>&nbsp;cos\u00ec da rendere pi\u00f9 immediata la comprensione del funzionamento dei detergenti solubili.&nbsp; Il risultato \u00e8 stata la creazione di un e-commerce che, nella sua semplicit\u00e0 e pulizia, risulta particolarmente distintivo e affine alla proposta valoriale di Axor, oltre che efficace dal punto di vista della user experience.<\/p>\n\n\n\n<p><strong>Non solo digitale: flyer, presentation box, etichette e packaging<br><\/strong>La collaborazione con Axor si \u00e8 concentrata, infine, anche sulla realizzazione della&nbsp;<strong>comunicazione offline&nbsp;<\/strong>del brand e, in particolare, di tutti i materiali comunicativi a stretto contatto con il cliente finale, come flyer d\u2019istruzione, presentation box, etichette dei flaconi e delle tabs e packaging.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.noooagency.com\/wp-content\/uploads\/2022\/08\/2-1024x1024.jpg\" alt=\"\" class=\"wp-image-1621\" srcset=\"https:\/\/www.noooagency.com\/wp-content\/uploads\/2022\/08\/2-1024x1024.jpg 1024w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2022\/08\/2-300x300.jpg 300w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2022\/08\/2-150x150.jpg 150w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2022\/08\/2-768x768.jpg 768w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2022\/08\/2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Perfettamente omologati e in linea con lo stile Axor, anche&nbsp;<strong>i contenuti offline si basano su linee morbide e colori pastello e incarnano il concetto di sostenibilit\u00e0 alla base del brand.<\/strong>&nbsp;<br><br>L\u2019innovazione di prodotto e la capacit\u00e0 di raccontarlo visivamente e materialmente ha trovato compimento nel premio&nbsp;<a href=\"https:\/\/www.adi-design.org\/blog\/adi-packaging-award-2022-vincitori.html\" target=\"_blank\" rel=\"noopener\"><strong>ADI PACKAGING DESIGN AWARD 2022<\/strong><\/a>, il premio che valorizza&nbsp;<strong>i packaging italiani pi\u00f9 innovativi&nbsp;<\/strong>e che mira a premiare anche gli aspetti del processo produttivo, valorizzando l\u2019innovazione e la ricerca.<br><br>Estremamente fieri dei risultati e apprezzamenti ottenuti da questo progetto, per noi di NOOO Agency \u00e8 stato davvero un piacere poter dare forma a un brand mosso da un impegno sociale cos\u00ec di valore, nella speranza di aver contribuito anche noi in piccola parte alla promozione di un futuro pi\u00f9 green per un domani pi\u00f9 limpido e brillante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi \u00e8 Axor&nbsp;Axor&nbsp;\u00e8 un\u2019azienda italiana che da pi\u00f9 di 40 anni si occupa di prodotti dedicati alla pulizia di diversi apparecchi domestici e industriali. Mossa fin dall\u2019origine da un profondo senso di responsabilit\u00e0 sociale e ambientale e forte di un\u2019esperienza consolidata nel tempo, Axor ha deciso di intraprendere un nuovo progetto che risponde alla necessit\u00e0 [&hellip;]<\/p>\n","protected":false},"featured_media":1620,"template":"","tags":[],"cat_borders":[],"class_list":["post-11540","noooborders","type-noooborders","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/noooborders\/11540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/noooborders"}],"about":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/types\/noooborders"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/media\/1620"}],"wp:attachment":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/media?parent=11540"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/tags?post=11540"},{"taxonomy":"cat_borders","embeddable":true,"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/cat_borders?post=11540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}