{"id":11469,"date":"2024-10-18T11:57:24","date_gmt":"2024-10-18T09:57:24","guid":{"rendered":"https:\/\/www.noooagency.com\/?post_type=noooborders&#038;p=11469"},"modified":"2026-03-12T18:47:25","modified_gmt":"2026-03-12T17:47:25","slug":"nooo-x-febal-casa-website-shooting-video","status":"publish","type":"noooborders","link":"https:\/\/www.noooagency.com\/noooborders\/nooo-x-febal-casa-website-shooting-video\/","title":{"rendered":"NOOO x Febal Casa: Website | Shooting | Video"},"content":{"rendered":"\n<p>Il marchio Febal \u00e8 diventato nel tempo un<strong> simbolo di affidabilit\u00e0 e valore<\/strong>, seguendo le orme della migliore produzione del design italiano, ed estendendo il suo know how anche nelle collezioni dedicate alla zona giorno e alla zona notte, per un Total Living di eccellenza.<\/p>\n\n\n\n<p>Quello tra NOOO e Colombini \u00e8 un sodalizio che dura gi\u00e0 da tempo, visti i progetti digitali sviluppati con <strong>Bontempi Casa<\/strong>.<\/p>\n\n\n\n<p>Il restyling completo del sito web <a href=\"http:\/\/febalcasa.com\/\" target=\"_blank\" rel=\"noopener\">febalcasa.com<\/a> conferma cos\u00ec l\u2019expertise dimostrata da NOOO all\u2019interno di questa industry nel corso degli anni, mettendo in risalto le <strong>competenze in ambito tecnologico<\/strong>, da sempre uno degli asset di maggior valore dell\u2019agenzia, ben <strong>supportate da un impianto creativo<\/strong> che consente di donare una forma rilevante e distintiva a tutte le produzioni.<\/p>\n\n\n\n<p>Nel corso dell\u2019edizione precedente della Design Week, nel 2023, abbiamo inoltre strutturato una strategia di content production per gli eventi organizzati da Febal Casa per il&nbsp;<strong>Fuori Salone del Mobile<\/strong>. Attraverso la nostra unit dedicata NOOO Lens abbiamo coordinato un\u2019attivit\u00e0 di copertura media con lo scopo di valorizzare ambiente, atmosfera e comunicazione dedicata per il format \u201c<strong><em>Empower your feeling with Febal casa<\/em><\/strong>\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/2-819x1024.jpg\" alt=\"\" class=\"wp-image-8858\" srcset=\"https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/2-819x1024.jpg 819w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/2-240x300.jpg 240w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/2-768x960.jpg 768w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/2-1229x1536.jpg 1229w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/2-1639x2048.jpg 1639w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/2-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<p><em>Continuare a collaborare su nuovi progetti con un gruppo di valore come Colombini, emblema del Made In Italy e in un industry cos\u00ec importante, non pu\u00f2 che essere per noi motivo di orgoglio. Il progetto ci ha visto coinvolti sin dalle prime fasi a livello strategico, con l\u2019obiettivo preciso di potenziare e migliorare la navigazione degli utenti, secondo i principali trend odierni in tema di UX e UI e in linea con la qualit\u00e0 che il brand vuole continuare a perseguire sul mercato<\/em>.<br><br><em>Allo stesso tempo si \u00e8 lavorato per aumentare la profondit\u00e0 delle informazioni sui sistemi, evidenziare la notevole modularit\u00e0 e componibilit\u00e0 dei prodotti e incentivare gli utenti a fissare un appuntamento in store L\u2019ecosistema del sito web si \u00e8 tradotto cos\u00ec traduce, cos\u00ec, in una composizione di esperienze fluide ed armoniose, trasmettendo un\u2019identit\u00e0 visiva unica e distintiva<\/em>.<\/p>\n\n\n\n<p>Questo il commento di Bruno Verneau, founder di NOOO.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/4-819x1024.jpg\" alt=\"\" class=\"wp-image-8860\" srcset=\"https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/4-819x1024.jpg 819w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/4-240x300.jpg 240w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/4-768x960.jpg 768w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/4-1229x1536.jpg 1229w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/4-1639x2048.jpg 1639w, https:\/\/www.noooagency.com\/wp-content\/uploads\/2024\/10\/4-scaled.jpg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Il marchio Febal \u00e8 diventato nel tempo un simbolo di affidabilit\u00e0 e valore, seguendo le orme della migliore produzione del design italiano, ed estendendo il suo know how anche nelle collezioni dedicate alla zona giorno e alla zona notte, per un Total Living di eccellenza. Quello tra NOOO e Colombini \u00e8 un sodalizio che dura [&hellip;]<\/p>\n","protected":false},"featured_media":8856,"template":"","tags":[],"cat_borders":[],"class_list":["post-11469","noooborders","type-noooborders","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/noooborders\/11469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/noooborders"}],"about":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/types\/noooborders"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/media\/8856"}],"wp:attachment":[{"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/media?parent=11469"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/tags?post=11469"},{"taxonomy":"cat_borders","embeddable":true,"href":"https:\/\/www.noooagency.com\/en\/wp-json\/wp\/v2\/cat_borders?post=11469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}